{"id":283845,"date":"2025-06-21T09:56:53","date_gmt":"2025-06-21T09:56:53","guid":{"rendered":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/21\/crossroads-worship-centre-43055\/"},"modified":"2025-06-21T09:56:53","modified_gmt":"2025-06-21T09:56:53","slug":"crossroads-worship-centre-43055","status":"publish","type":"post","link":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/21\/crossroads-worship-centre-43055\/","title":{"rendered":"Crossroads Worship Centre 43055"},"content":{"rendered":"<p>Churches<\/p>\n<p>Crossroads Worship Centre<br \/>\n858 Garfield Ave, Newark, OH 43055<br \/>\n<a href=\"https:\/\/duckduckgo.com\/?t=h_&amp;q=Crossroads Worship Centre 858 Garfield Ave, Newark, OH 43055\">Crossroads Worship Centre Search<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/search\/top\/?q=Crossroads Worship Centre 858 Garfield Ave, Newark, OH 43055\">Facebook Crossroads Worship Centre Search <\/a><br \/>\n<form role=\"search\" method=\"get\" class=\"search-form\" action=\"https:\/\/faithoklahoma.com\/directory\/\">\n\t\t\t\t<label>\n\t\t\t\t\t<span class=\"screen-reader-text\">Search for:<\/span>\n\t\t\t\t\t<input type=\"search\" class=\"search-field\" placeholder=\"Search &hellip;\" value=\"\" name=\"s\" \/>\n\t\t\t\t<\/label>\n\t\t\t\t<input type=\"submit\" class=\"search-submit\" value=\"Search\" \/>\n\t\t\t<input type=\"hidden\" name=\"id\" value=\"3\" \/><\/form><\/p>\n<p>untested url =<br \/>\nuntested facebook link <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Churches Crossroads Worship Centre 858 Garfield Ave, Newark, OH 43055 Crossroads Worship Centre Search Facebook Crossroads Worship Centre Search untested url = untested facebook link<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-283845","post","type-post","status-publish","format-standard","hentry","category-ohio"],"_links":{"self":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/283845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/comments?post=283845"}],"version-history":[{"count":0,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/283845\/revisions"}],"wp:attachment":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/media?parent=283845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/categories?post=283845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/tags?post=283845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}