{"id":148125,"date":"2025-06-20T23:01:27","date_gmt":"2025-06-20T23:01:27","guid":{"rendered":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/templo-emanuel-dios-con-nosotros-de-rgc-78582\/"},"modified":"2025-06-20T23:01:27","modified_gmt":"2025-06-20T23:01:27","slug":"templo-emanuel-dios-con-nosotros-de-rgc-78582","status":"publish","type":"post","link":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/templo-emanuel-dios-con-nosotros-de-rgc-78582\/","title":{"rendered":"Templo Emanuel Dios con Nosotros de RGC 78582"},"content":{"rendered":"<p>Churches<\/p>\n<p>Templo Emanuel Dios con Nosotros de RGC<br \/>\n1989 Embassy St, Rio Grande City, TX 78582<br \/>\n<a href=\"https:\/\/duckduckgo.com\/?t=h_&amp;q=Templo Emanuel Dios con Nosotros de RGC 1989 Embassy St, Rio Grande City, TX 78582\">Templo Emanuel Dios con Nosotros de RGC Search<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/search\/top\/?q=Templo Emanuel Dios con Nosotros de RGC 1989 Embassy St, Rio Grande City, TX 78582\">Facebook Templo Emanuel Dios con Nosotros de RGC Search <\/a><br \/>\n<form role=\"search\" method=\"get\" class=\"search-form\" action=\"https:\/\/faithoklahoma.com\/directory\/\">\n\t\t\t\t<label>\n\t\t\t\t\t<span class=\"screen-reader-text\">Search for:<\/span>\n\t\t\t\t\t<input type=\"search\" class=\"search-field\" placeholder=\"Search &hellip;\" value=\"\" name=\"s\" \/>\n\t\t\t\t<\/label>\n\t\t\t\t<input type=\"submit\" class=\"search-submit\" value=\"Search\" \/>\n\t\t\t<input type=\"hidden\" name=\"id\" value=\"3\" \/><\/form><\/p>\n<p>untested url =<br \/>\nuntested facebook link <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Churches Templo Emanuel Dios con Nosotros de RGC 1989 Embassy St, Rio Grande City, TX 78582 Templo Emanuel Dios con Nosotros de RGC Search Facebook Templo Emanuel Dios con Nosotros de RGC Search untested url = untested facebook link<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-148125","post","type-post","status-publish","format-standard","hentry","category-texas"],"_links":{"self":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/148125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/comments?post=148125"}],"version-history":[{"count":0,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/148125\/revisions"}],"wp:attachment":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/media?parent=148125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/categories?post=148125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/tags?post=148125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}