{"id":148095,"date":"2025-06-20T23:01:19","date_gmt":"2025-06-20T23:01:19","guid":{"rendered":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/ministerio-international-la-cosecha-kirbyville-tx-75956\/"},"modified":"2025-06-20T23:01:19","modified_gmt":"2025-06-20T23:01:19","slug":"ministerio-international-la-cosecha-kirbyville-tx-75956","status":"publish","type":"post","link":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/ministerio-international-la-cosecha-kirbyville-tx-75956\/","title":{"rendered":"Ministerio International La Cosecha Kirbyville Tx 75956"},"content":{"rendered":"<p>Churches<\/p>\n<p>Ministerio International La Cosecha Kirbyville Tx<br \/>\n301 E Main St, Kirbyville, TX 75956<br \/>\n<a href=\"https:\/\/duckduckgo.com\/?t=h_&amp;q=Ministerio International La Cosecha Kirbyville Tx 301 E Main St, Kirbyville, TX 75956\">Ministerio International La Cosecha Kirbyville Tx Search<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/search\/top\/?q=Ministerio International La Cosecha Kirbyville Tx 301 E Main St, Kirbyville, TX 75956\">Facebook Ministerio International La Cosecha Kirbyville Tx Search <\/a><br \/>\n<form role=\"search\" method=\"get\" class=\"search-form\" action=\"https:\/\/faithoklahoma.com\/directory\/\">\n\t\t\t\t<label>\n\t\t\t\t\t<span class=\"screen-reader-text\">Search for:<\/span>\n\t\t\t\t\t<input type=\"search\" class=\"search-field\" placeholder=\"Search &hellip;\" value=\"\" name=\"s\" \/>\n\t\t\t\t<\/label>\n\t\t\t\t<input type=\"submit\" class=\"search-submit\" value=\"Search\" \/>\n\t\t\t<input type=\"hidden\" name=\"id\" value=\"3\" \/><\/form><\/p>\n<p>untested url =https:\/\/www.facebook.com\/people\/La-Cosecha-Kirbyville\/100072278820506\/<br \/>\nuntested facebook link <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Churches Ministerio International La Cosecha Kirbyville Tx 301 E Main St, Kirbyville, TX 75956 Ministerio International La Cosecha Kirbyville Tx Search Facebook Ministerio International La Cosecha Kirbyville Tx Search untested url =https:\/\/www.facebook.com\/people\/La-Cosecha-Kirbyville\/100072278820506\/ untested facebook link<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-148095","post","type-post","status-publish","format-standard","hentry","category-texas"],"_links":{"self":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/148095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/comments?post=148095"}],"version-history":[{"count":0,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/148095\/revisions"}],"wp:attachment":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/media?parent=148095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/categories?post=148095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/tags?post=148095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}