{"id":147540,"date":"2025-06-20T22:59:26","date_gmt":"2025-06-20T22:59:26","guid":{"rendered":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/iglesia-apostolica-fuente-de-vida-78221\/"},"modified":"2025-06-20T22:59:26","modified_gmt":"2025-06-20T22:59:26","slug":"iglesia-apostolica-fuente-de-vida-78221","status":"publish","type":"post","link":"https:\/\/faithoklahoma.com\/directory\/2025\/06\/20\/iglesia-apostolica-fuente-de-vida-78221\/","title":{"rendered":"Iglesia Apostolica Fuente de Vida 78221"},"content":{"rendered":"<p>Churches<\/p>\n<p>Iglesia Apostolica Fuente de Vida<br \/>\n339 W Hutchins Pl, San Antonio, TX 78221<br \/>\n<a href=\"https:\/\/duckduckgo.com\/?t=h_&amp;q=Iglesia Apostolica Fuente de Vida 339 W Hutchins Pl, San Antonio, TX 78221\">Iglesia Apostolica Fuente de Vida Search<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/search\/top\/?q=Iglesia Apostolica Fuente de Vida 339 W Hutchins Pl, San Antonio, TX 78221\">Facebook Iglesia Apostolica Fuente de Vida Search <\/a><br \/>\n<form role=\"search\" method=\"get\" class=\"search-form\" action=\"https:\/\/faithoklahoma.com\/directory\/\">\n\t\t\t\t<label>\n\t\t\t\t\t<span class=\"screen-reader-text\">Search for:<\/span>\n\t\t\t\t\t<input type=\"search\" class=\"search-field\" placeholder=\"Search &hellip;\" value=\"\" name=\"s\" \/>\n\t\t\t\t<\/label>\n\t\t\t\t<input type=\"submit\" class=\"search-submit\" value=\"Search\" \/>\n\t\t\t<input type=\"hidden\" name=\"id\" value=\"3\" \/><\/form><\/p>\n<p>untested url =<br \/>\nuntested facebook link <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Churches Iglesia Apostolica Fuente de Vida 339 W Hutchins Pl, San Antonio, TX 78221 Iglesia Apostolica Fuente de Vida Search Facebook Iglesia Apostolica Fuente de Vida Search untested url = untested facebook link<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-147540","post","type-post","status-publish","format-standard","hentry","category-texas"],"_links":{"self":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/147540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/comments?post=147540"}],"version-history":[{"count":0,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/posts\/147540\/revisions"}],"wp:attachment":[{"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/media?parent=147540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/categories?post=147540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faithoklahoma.com\/directory\/wp-json\/wp\/v2\/tags?post=147540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}